{"id":508,"date":"2018-11-16T08:49:57","date_gmt":"2018-11-16T08:49:57","guid":{"rendered":"http:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387.jpg"},"modified":"2018-11-16T09:06:18","modified_gmt":"2018-11-16T09:06:18","slug":"vi-borze-387","status":"inherit","type":"attachment","link":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/vi-borze-387\/","title":{"rendered":"VI B\u00f6rze 387"},"author":5,"comment_status":"open","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false},"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387.jpg' rel=\"wpdevart_lightbox\"><img width=\"300\" height=\"200\" src=\"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-300x200.jpg 300w, https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-768x512.jpg 768w, https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":683,"file":"2018\/11\/VI-B\u00f6rze-387.jpg","sizes":{"thumbnail":{"file":"VI-B\u00f6rze-387-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-150x150.jpg"},"medium":{"file":"VI-B\u00f6rze-387-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-300x200.jpg"},"medium_large":{"file":"VI-B\u00f6rze-387-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-768x512.jpg"},"large":{"file":"VI-B\u00f6rze-387-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387-1024x683.jpg"},"full":{"file":"VI-B\u00f6rze-387.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-content\/uploads\/sites\/4\/2018\/11\/VI-B\u00f6rze-387.jpg","_links":{"self":[{"href":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-json\/wp\/v2\/media\/508"}],"collection":[{"href":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csepelivaroskep.hu\/szabomagda\/wp-json\/wp\/v2\/comments?post=508"}]}}